{"id":291,"date":"2019-11-26T14:37:35","date_gmt":"2019-11-26T17:37:35","guid":{"rendered":"https:\/\/laplataac.org\/laplataac\/?p=291"},"modified":"2019-11-26T14:38:53","modified_gmt":"2019-11-26T17:38:53","slug":"sin-limites-asociacion-aragonesa-de-altas-capacidades","status":"publish","type":"post","link":"https:\/\/laplataac.org\/laplataac\/sin-limites-asociacion-aragonesa-de-altas-capacidades\/","title":{"rendered":"Sin L\u00edmites | Asociaci\u00f3n Aragonesa de Altas Capacidades"},"content":{"rendered":"\n<blockquote class=\"wp-block-quote\"><p>Con la denominaci\u00f3n <strong>Sin L\u00edmites<\/strong>, Asociaci\u00f3n Aragonesa  de Altas Capacidades, se constituye una ASOCIACION al amparo de la Ley  Org\u00e1nica 1\/2002, de 22 de marzo, y normas complementarias, con capacidad  jur\u00eddica y plena capacidad de obrar, careciendo de \u00e1nimo de lucro. La  Asociaci\u00f3n, como entidad abierta a toda la sociedad, no tiene  adscripci\u00f3n, filiaci\u00f3n, ni tan siquiera posicionamiento ninguno frente a  ideolog\u00edas, creencias o corrientes de pensamiento, sean cuales fueren.  Esto no es obst\u00e1culo para que, en la defensa de intereses comunes, se  puedan establecer v\u00ednculos con otras entidades que si los tengan.<\/p><cite><a rel=\"noreferrer noopener\" aria-label=\" (se abre en una nueva pesta\u00f1a)\" href=\"https:\/\/sinlimites.altacapacidad.net\/\" target=\"_blank\">Sitio web<\/a><\/cite><\/blockquote>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con la denominaci\u00f3n Sin L\u00edmites, Asociaci\u00f3n Aragonesa de Altas Capacidades, se constituye una ASOCIACION al amparo de la Ley Org\u00e1nica 1\/2002, de 22 de marzo, y normas complementarias, con capacidad jur\u00eddica y plena capacidad de obrar, careciendo de \u00e1nimo de lucro. La Asociaci\u00f3n, como entidad abierta a toda la sociedad, no tiene adscripci\u00f3n, filiaci\u00f3n, ni &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/laplataac.org\/laplataac\/sin-limites-asociacion-aragonesa-de-altas-capacidades\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abSin L\u00edmites | Asociaci\u00f3n Aragonesa de Altas Capacidades\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15,4],"tags":[19,36,35],"_links":{"self":[{"href":"https:\/\/laplataac.org\/laplataac\/wp-json\/wp\/v2\/posts\/291"}],"collection":[{"href":"https:\/\/laplataac.org\/laplataac\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laplataac.org\/laplataac\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laplataac.org\/laplataac\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/laplataac.org\/laplataac\/wp-json\/wp\/v2\/comments?post=291"}],"version-history":[{"count":3,"href":"https:\/\/laplataac.org\/laplataac\/wp-json\/wp\/v2\/posts\/291\/revisions"}],"predecessor-version":[{"id":294,"href":"https:\/\/laplataac.org\/laplataac\/wp-json\/wp\/v2\/posts\/291\/revisions\/294"}],"wp:attachment":[{"href":"https:\/\/laplataac.org\/laplataac\/wp-json\/wp\/v2\/media?parent=291"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laplataac.org\/laplataac\/wp-json\/wp\/v2\/categories?post=291"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laplataac.org\/laplataac\/wp-json\/wp\/v2\/tags?post=291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}